{"id":3351,"date":"2022-10-28T17:35:01","date_gmt":"2022-10-28T17:35:01","guid":{"rendered":"https:\/\/gonewyork.com\/neighborhood\/lower-east-side-nyc-nachbarschaftsfuehrer\/"},"modified":"2025-08-20T15:24:01","modified_gmt":"2025-08-20T15:24:01","slug":"lower-east-side-nyc-nachbarschaftsfuehrer","status":"publish","type":"neighborhood","link":"https:\/\/gonewyork.com\/de\/neighborhood\/lower-east-side-nyc-nachbarschaftsfuehrer\/","title":{"rendered":"Lower East Side, NYC Nachbarschaftsf\u00fchrer"},"content":{"rendered":"\n<p>Die Lower East Side von Manhattan blickt auf eine lange, reiche Geschichte zur\u00fcck. Es war der Ort, an dem sich viele Einwanderer nach ihrer Ankunft in den Vereinigten Staaten niederlie\u00dfen, und zu einem bestimmten Zeitpunkt war es die Heimat einer bemerkenswerten j\u00fcdischen Gemeinde. Das Viertel hat sich heute zu einem beliebten Ziel f\u00fcr das Nachtleben entwickelt und ist der Standort einiger der besten Rockclubs, trendigsten Restaurants und angesagtesten Bars der Stadt. Mehrere <a href=\"https:\/\/gonewyork.com\/de\/museen-in-new-york-city\/\" data-type=\"page\" data-id=\"395\">angesehene Museen<\/a> befinden sich ebenfalls innerhalb der traditionellen geografischen Grenzen der Lower East Side.   <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/gonewyork.com\/wp-content\/uploads\/2022\/09\/nyc-neighborhood-Lower-East-Side-IMG_3253-1024x768.jpg\" alt=\"\" class=\"wp-image-1792\" srcset=\"https:\/\/gonewyork.com\/wp-content\/uploads\/2022\/09\/nyc-neighborhood-Lower-East-Side-IMG_3253-1024x768.jpg 1024w, https:\/\/gonewyork.com\/wp-content\/uploads\/2022\/09\/nyc-neighborhood-Lower-East-Side-IMG_3253-300x225.jpg 300w, https:\/\/gonewyork.com\/wp-content\/uploads\/2022\/09\/nyc-neighborhood-Lower-East-Side-IMG_3253-768x576.jpg 768w, https:\/\/gonewyork.com\/wp-content\/uploads\/2022\/09\/nyc-neighborhood-Lower-East-Side-IMG_3253-1536x1152.jpg 1536w, https:\/\/gonewyork.com\/wp-content\/uploads\/2022\/09\/nyc-neighborhood-Lower-East-Side-IMG_3253-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>FFB36045-AE28-49D1-AA1B-878D9040EA16<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\"><strong>Die Geschichte des Viertels Lower East Side<\/strong><\/h2>\n\n<p>Eine betr\u00e4chtliche Anzahl der Einwanderer, die zwischen 1840 und 1920 aus Europa in die Vereinigten Staaten zogen und sich in New York City niederlie\u00dfen, lebten zumindest eine Zeit lang in der N\u00e4he der Lower East Side. Zu diesen Einwanderern geh\u00f6rten gro\u00dfe Bev\u00f6lkerungsgruppen aus Deutschland, Italien, der Slowakei und der Ukraine sowie eine gro\u00dfe Anzahl j\u00fcdischer Menschen aus Osteuropa, die alle ihre unterschiedlichen Glaubensrichtungen, Hintergr\u00fcnde und Erfahrungen in die Lower East Side einbrachten. Zu Beginn des 20. Jahrhunderts war das Leben hier recht schwierig, da die Lower East Side dicht besiedelt war und die Lebensbedingungen oft eher rau und unangenehm waren. Tats\u00e4chlich wurden diese schwierigen Lebensbedingungen von Sozialreformern wie Jacob Riis h\u00e4ufig dokumentiert und kritisiert.   <\/p>\n\n<p>Doch wie so viele andere Viertel von New York City begann sich der Charakter der Lower East Side mit der Zeit zu ver\u00e4ndern, da viele Alteingesessene wegzogen und sich die Gentrifizierung einschlich. Heute ist die Lower East Side ein sich entwickelnder Ort, an dem das Bauen der alten Welt oft auf zeitgen\u00f6ssische Trends trifft. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Erkundung der Lower East Side<\/strong><\/h2>\n\n<p>Eine der sch\u00f6nsten Sammlungen zeitgen\u00f6ssischer Kunst in New York City befindet sich im <a href=\"https:\/\/gonewyork.com\/de\/museum\/neues-museum\/\" data-type=\"museum\" data-id=\"1324\">New Museum<\/a>, das seit \u00fcber 15 Jahren in seinem gefeierten, hochmodernen Geb\u00e4ude in der 235 Bowery untergebracht ist. Das Neue Museum verf\u00fcgt \u00fcber eine herausragende Dauerausstellung von mehreren tausend Werken, aber sein gr\u00f6\u00dfter Beitrag zur zeitgen\u00f6ssischen Kunst sind die bemerkenswerten Wechselausstellungen, die es das ganze Jahr \u00fcber organisiert. <\/p>\n\n<p>Das Tenement Museum der Lower East Side ist eine einzigartige Attraktion, die sowohl bewegend als auch aufschlussreich ist. Das Tenement Museum besteht aus zwei Mietskasernen, die heute National Historic Landmarks sind, und Besucher k\u00f6nnen sich durch die historischen Geb\u00e4ude bewegen und dabei mehr \u00fcber die Geschichten der Arbeiterklasse (oft Einwanderer) erfahren, die diesen Ort ab etwa 1850 ihr Zuhause nannten. Das Leben in dieser Art von Geb\u00e4uden war nicht einfach, aber die Menschen, die aus den Mietskasernen kamen, haben viel dazu beigetragen, die Welt, in der wir heute leben, zu formen.  <\/p>\n\n<p>Ebenfalls auf der Lower East Side befindet sich das <a href=\"https:\/\/gonewyork.com\/de\/museum\/internationales-zentrum-fuer-fotografie-ny\/\" data-type=\"museum\" data-id=\"1330\">International Center of Photography<\/a>. Seit seiner Gr\u00fcndung vor fast 50 Jahren widmet sich das ICP dem, was es als &#8222;betroffene Fotografie&#8220; bezeichnet \u2013 also Werke der visuellen Kultur, die uns innehalten und zweimal \u00fcber die Welt um uns herum nachdenken lassen. Die Exponate, die im ICP ausgestellt werden, sind vielf\u00e4ltig und ver\u00e4ndern sich st\u00e4ndig.  <\/p>\n\n<p>Die Lower East Side befindet sich entlang des East River direkt s\u00fcdlich des East Village. Im Westen liegen <strong>NoLita<\/strong>, <strong>Little Italy<\/strong> und <strong>Chinatown<\/strong>. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Restaurants in der Lower East Side<\/strong><\/h2>\n\n<p>Eine weitere gro\u00dfe Attraktion der modernen Lower East Side ist das pulsierende Nachtleben. Die Lower East Side ist voll von gro\u00dfartigen Orten, um ein k\u00f6stliches Essen zu ergattern, mit angesehenen haitianischen, puerto-ricanischen, s\u00fcdindischen, griechischen und italienischen Restaurants, die alle in einem Umkreis von wenigen Blocks nahe beieinander liegen. Wenn Sie auf der Suche nach einer getr\u00e4nkezentrierten Atmosph\u00e4re sind, gibt es hier auch unz\u00e4hlige Bars zu verschiedenen Preisen, aus denen Sie w\u00e4hlen k\u00f6nnen.  <\/p>\n\n<p>Zwei der gastronomischen Institutionen der Lower East Side sind das weltber\u00fchmte Katz&#8217;s Delicatessen, das seit fast 100 Jahren an seinem jetzigen Standort in Betrieb ist und in dieser Zeit zu einem Ph\u00e4nomen der Popkultur geworden ist; und Russ &amp; Daughters, ein j\u00fcdisches Gourmet-Lebensmittelgesch\u00e4ft, dessen Gesch\u00e4ft in der Lower East Side (179 East Houston Street) 1920 er\u00f6ffnet wurde.<\/p>\n\n<p>Essen und Trinken sind ein so gro\u00dfer Teil des Erlebnisses in der Lower East Side \u2013 damals wie heute \u2013, dass es mehrere gef\u00fchrte Rundg\u00e4nge durch das Viertel gibt, die sich speziell auf die lokale K\u00fcche und Spezialit\u00e4ten der Region konzentrieren. Es gibt sogar eine Bagel-Tour durch die Lower East Side, die Sie unternehmen k\u00f6nnen! <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Einkaufen in der Lower East Side<\/strong><\/h2>\n\n<p>Viele w\u00fcrden argumentieren, dass die Einkaufsszene der Lower East Side heute von einem drei Blocks langen Abschnitt der Orchard Street dominiert wird, der sich unmittelbar s\u00fcdlich der Broome Street befindet. Diese lebendige Gegend ist vollgepackt mit modischen Boutiquen wie LAAMS und Daniella Kallmeyers gleichnamigem Gesch\u00e4ft sowie dem Geschenkdesign-Shop Coming Soon, dem Wohndekorationsgesch\u00e4ft November 19 Shop und vielen, vielen innovativen Marken. <\/p>\n\n<p>Neben diesen modischen Reisezielen bietet die Lower East Side auch eine gro\u00dfe Auswahl an Kunstgalerien, Schneiderateliers, Vintage-Bekleidungsgesch\u00e4ften, Antiquit\u00e4tengesch\u00e4ften und Buchhandlungen. F\u00fcr den kulinarisch veranlagten Shopper ist der Essex Market ein historischer Markt, auf dem Spezialit\u00e4ten, K\u00e4se, Obst und Gem\u00fcse, Fisch, Fleisch und vieles mehr verkauft werden. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Erkunden Sie die Lower East Side wie ein Einheimischer<\/strong><\/h2>\n\n<ul class=\"wp-block-list\"><li>Die Einfahrt (f\u00fcr Radfahrer und Fu\u00dfg\u00e4nger) zur Williamsburg Bridge in Manhattan befindet sich auf der Lower East Side an der Kreuzung der Clinton Street und der Delancey Street. Zu Fu\u00df oder mit dem Fahrrad \u00fcber die Williamsburg Bridge zu gehen, kann ein sch\u00f6nes Erlebnis sein, da sie einen spektakul\u00e4ren Blick auf New York City in mehrere Richtungen bietet. <\/li><li>Einige der besten Rockclubs in ganz New York City befinden sich in der Lower East Side. Veranstaltungsorte wie der Bowery Ballroom, die Mercury Lounge, die Rockwood Music Hall und die Bowery Electric beherbergen regelm\u00e4\u00dfig Acts, die man gesehen haben muss, also schauen Sie sich vor Ihrem Besuch die offiziellen Websites an, um eine Liste der bevorstehenden Shows zu erhalten, um mehr dar\u00fcber zu erfahren, wer in der Gegend live spielen k\u00f6nnte, wenn Sie in der Stadt sind. <\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Einst die Heimat von Generationen von New Yorker Einwanderern aus der Arbeiterklasse, ist die Lower East Side heute ein beliebtes Ziel f\u00fcr das Nachtleben, das f\u00fcr seine vielseitige Auswahl an Museen, Musikveranstaltungsorten, trendigen Restaurants und angesagten Bars bekannt ist.<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","borough":[39],"class_list":["post-3351","neighborhood","type-neighborhood","status-publish","hentry","borough-manhattan"],"acf":[],"_links":{"self":[{"href":"https:\/\/gonewyork.com\/de\/wp-json\/wp\/v2\/neighborhood\/3351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gonewyork.com\/de\/wp-json\/wp\/v2\/neighborhood"}],"about":[{"href":"https:\/\/gonewyork.com\/de\/wp-json\/wp\/v2\/types\/neighborhood"}],"wp:attachment":[{"href":"https:\/\/gonewyork.com\/de\/wp-json\/wp\/v2\/media?parent=3351"}],"wp:term":[{"taxonomy":"borough","embeddable":true,"href":"https:\/\/gonewyork.com\/de\/wp-json\/wp\/v2\/borough?post=3351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}